{"id":53,"date":"2016-04-26T10:29:28","date_gmt":"2016-04-26T10:29:28","guid":{"rendered":"http:\/\/www.derakhshandeh.ir\/fa\/?p=53"},"modified":"2016-04-30T10:32:38","modified_gmt":"2016-04-30T10:32:38","slug":"%d9%be%d9%88%d8%b1%d8%a7%d9%86-%d8%af%d8%b1%d8%ae%d8%b4%d9%86%d8%af%d9%87-%da%a9%d8%a7%d8%b1%da%af%d8%a7%d9%87-%d8%af%d8%a7%d8%b1%d8%a7%d9%84%d9%81%d9%86%d9%88%d9%86-%d9%86","status":"publish","type":"post","link":"http:\/\/pouranderakhshandeh.ir\/fa\/53\/%d9%be%d9%88%d8%b1%d8%a7%d9%86-%d8%af%d8%b1%d8%ae%d8%b4%d9%86%d8%af%d9%87-%da%a9%d8%a7%d8%b1%da%af%d8%a7%d9%87-%d8%af%d8%a7%d8%b1%d8%a7%d9%84%d9%81%d9%86%d9%88%d9%86-%d9%86\/","title":{"rendered":"\u067e\u0648\u0631\u0627\u0646 \u062f\u0631\u062e\u0634\u0646\u062f\u0647 \u062f\u0631 \u06a9\u0627\u0631\u06af\u0627\u0647 \u00ab\u062f\u0627\u0631\u0627\u0644\u0641\u0646\u0648\u0646\u00bb: \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0645 \u0646\u0633\u0628\u062a \u0628\u0647 \u0632\u0646\u062f\u06af\u06cc \u0645\u0631\u062f\u0645 \u0628\u06cc\u200c\u062a\u0641\u0627\u0648\u062a \u0628\u0627\u0634\u0645"},"content":{"rendered":"<p>\u06a9\u0627\u0631\u06af\u0631\u062f\u0627\u0646 \u0641\u06cc\u0644\u0645 \u0633\u06cc\u0646\u0645\u0627\u06cc\u06cc \u00ab\u0647\u06cc\u0633! \u062f\u062e\u062a\u0631\u0647\u0627 \u0641\u0631\u06cc\u0627\u062f \u0646\u0645\u06cc\u200c\u0632\u0646\u0646\u062f\u00bb \u062a\u0627\u06a9\u06cc\u062f \u06a9\u0631\u062f \u0641\u06cc\u0644\u0645\u0633\u0627\u0632 \u0628\u0627\u06cc\u062f \u0628\u0627 \u0633\u0648\u0698\u0647 \u0632\u0646\u062f\u06af\u06cc \u06a9\u0646\u062f.<\/p>\n<p>\u067e\u0648\u0631\u0627\u0646 \u062f\u0631\u062e\u0634\u0646\u062f\u0647 \u0634\u0646\u0628\u0647 \u0686\u0647\u0627\u0631\u0645 \u0627\u0631\u062f\u06cc\u0628\u0647\u0634\u062a\u200c\u0645\u0627\u0647 \u0628\u0627 \u062d\u0636\u0648\u0631 \u062f\u0631 \u06a9\u0627\u0631\u06af\u0627\u0647 \u00ab\u062f\u0627\u0631\u0627\u0644\u0641\u0646\u0648\u0646\u00bb \u0636\u0645\u0646 \u062a\u0634\u06a9\u0631 \u0627\u0632 \u0628\u0631\u06af\u0632\u0627\u0631\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u062c\u0634\u0646\u0648\u0627\u0631\u0647 \u062c\u0647\u0627\u0646\u06cc \u0641\u06cc\u0644\u0645 \u0641\u062c\u0631 \u06af\u0641\u062a: \u0627\u0632 \u0627\u06cc\u0646\u06a9\u0647 \u062c\u0634\u0646\u0648\u0627\u0631\u0647 \u062c\u0647\u0627\u0646\u06cc \u0641\u062c\u0631 \u0627\u06cc\u0646 \u0641\u0631\u0635\u062a \u0631\u0627 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u0627\u06cc\u0646 \u062c\u0645\u0639 \u0642\u0631\u0627\u0631 \u062f\u0627\u062f \u062a\u0627 \u0641\u06cc\u0644\u0645\u0633\u0627\u0632\u0627\u0646 \u0622\u06cc\u0646\u062f\u0647 \u0627\u06cc\u0631\u0627\u0646\u06cc \u0648 \u062e\u0627\u0631\u062c\u06cc \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u062f\u0631 \u0627\u06cc\u0646 \u0645\u062c\u0627\u0644 \u0627\u0646\u062f\u06cc\u0634\u0647 \u0627\u0646\u062f\u0648\u0632\u06cc \u06a9\u0646\u0646\u062f \u0648 \u0628\u0627 \u0627\u0633\u0627\u062a\u06cc\u062f \u0645\u062e\u062a\u0644\u0641 \u062f\u0631 \u0645\u0648\u0631\u062f \u062a\u062c\u0631\u0628\u06cc\u0627\u062a\u0634\u0627\u0646 \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0631\u0642\u0631\u0627\u0631 \u06a9\u0646\u0646\u062f \u0648 \u0641\u06cc\u0644\u0645 \u0628\u0633\u0627\u0632\u0646\u062f\u060c \u062e\u0648\u0634\u062d\u0627\u0644\u0645.<\/p>\n<p>\u0627\u0648 \u06af\u0641\u062a: \u062f\u0631 \u062f\u0648\u0631\u0647 \u0627\u06cc \u06a9\u0647 \u0645\u0627 \u06a9\u0627\u0631\u0645\u0627\u0646 \u0631\u0627 \u0622\u063a\u0627\u0632 \u06a9\u0631\u062f\u06cc\u0645 \u0686\u0646\u06cc\u0646 \u0641\u0631\u0635\u062a \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc\u0645\u0627\u0646 \u067e\u06cc\u0634 \u0646\u0645\u06cc\u200c\u0622\u0645\u062f \u06a9\u0647 \u0627\u0632 \u062a\u062c\u0631\u0628\u06cc\u0627\u062a \u067e\u06cc\u0634\u06a9\u0633\u0648\u062a\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u0645\u060c \u062d\u0631\u0641 \u0628\u0632\u0646\u06cc\u0645 \u0648 \u0633\u0648\u0627\u0644 \u0628\u067e\u0631\u0633\u06cc\u0645. \u0647\u0645\u0647 \u0627\u06cc\u0646 \u0631\u0648\u0646\u062f\u00a0 \u0631\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u062a\u062c\u0631\u0628\u06cc \u0637\u06cc \u06a9\u0631\u062f\u06cc\u0645\u060c \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0627\u06cc\u0646 \u0641\u0631\u0635\u062a \u0631\u0627 \u0628\u0647 \u0634\u0645\u0627 \u062a\u0628\u0631\u06cc\u06a9 \u0645\u06cc\u200c\u06af\u0648\u06cc\u0645 \u0648 \u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u0645 \u0627\u0632 \u0622\u0646 \u0646\u0647\u0627\u06cc\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0631\u0627 \u0628\u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u0627\u0648 \u062f\u0631 \u0622\u063a\u0627\u0632 \u0633\u062e\u0646\u0627\u0646 \u062e\u0648\u062f \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u0627\u06cc\u0646\u06a9\u0647 \u0641\u06cc\u0644\u0645\u0633\u0627\u0632\u06cc \u062d\u0631\u0641\u0647 \u0628\u0633\u06cc\u0627\u0631 \u0633\u062e\u062a\u06cc \u0627\u0633\u062a\u060c \u06af\u0641\u062a: \u0641\u06cc\u0644\u0645\u0633\u0627\u0632\u06cc \u0639\u0631\u0642\u200c\u0631\u06cc\u0632\u0627\u0646 \u0631\u0648\u062d\u06cc \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0644\u062d\u0638\u0647 \u0627\u06cc \u0631\u0627 \u0637\u0631\u0627\u062d\u06cc\u060c \u062a\u0648\u0644\u06cc\u062f \u0648 \u0628\u0647 \u062f\u0646\u06cc\u0627\u06cc \u067e\u06cc\u0631\u0627\u0645\u0648\u0646 \u0645\u0639\u0631\u0641\u06cc \u06a9\u0646\u06cc\u062f. \u0641\u06cc\u0644\u0645\u0633\u0627\u0632\u06cc \u06cc\u06a9 \u0632\u0627\u06cc\u0634 \u0627\u0633\u062a. \u0632\u0627\u06cc\u0634\u06cc \u06a9\u0647 \u0633\u062e\u062a\u06cc \u0647\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u062f\u0627\u0631\u062f.<\/p>\n<p>\u0627\u06cc\u0646 \u06a9\u0627\u0631\u06af\u0631\u062f\u0627\u0646 \u0627\u062f\u0627\u0645\u0647 \u062f\u0627\u062f: \u0641\u06cc\u0644\u0645\u0633\u0627\u0632\u06cc \u067e\u0646\u062c\u0631\u0647\u200c\u0627\u06cc \u0631\u0648 \u0628\u0647 \u0628\u06cc\u0631\u0648\u0646 \u0627\u0633\u062a. \u067e\u0646\u062c\u0631\u0647 \u0627\u06cc \u06a9\u0647 \u0642\u0631\u0627\u0631 \u0627\u0633\u062a \u0634\u0645\u0627 \u0622\u0646 \u0631\u0627 \u0628\u0627\u0632 \u06a9\u0646\u06cc\u062f \u0628\u0627\u06cc\u062f \u067e\u0646\u062c\u0631\u0647\u200c\u0627\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0642\u0628\u0644\u0627 \u06a9\u0633\u06cc \u0622\u0646 \u0631\u0627 \u0646\u062f\u06cc\u062f\u0647 \u0628\u0627\u0634\u062f. \u067e\u0646\u062c\u0631\u0647\u200c\u0627\u06cc \u0628\u0627\u0632 \u0645\u06cc \u06a9\u0646\u06cc\u062f \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u0628\u06af\u0648\u06cc\u06cc\u062f \u062f\u0646\u06cc\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f \u0686\u06af\u0648\u0646\u0647 \u062f\u06cc\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f\u061f \u0622\u06cc\u0627 \u0622\u0641\u062a\u0627\u0628\u06cc \u0627\u0633\u062a \u06cc\u0627 \u062a\u06cc\u0631\u0647 \u0648 \u06af\u0631\u0641\u062a\u0647. \u0628\u0647 \u0686\u0647 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a\u06cc \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u062f \u062a\u0627 \u0622\u062f\u0645 \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0642\u0631\u0627\u0631 \u0627\u0633\u062a \u062f\u0631 \u0622\u0646 \u0632\u0646\u062f\u06af\u06cc \u06a9\u0646\u0646\u062f \u0622\u0631\u0627\u0645\u0634 \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f.<\/p>\n<p>\u062f\u0631\u062e\u0634\u0646\u062f\u0647 \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u0633\u0648\u0698\u0647 \u06cc\u0627\u0628\u06cc \u06af\u0641\u062a: \u0627\u0645\u0631\u0648\u0632 \u0645\u06cc \u062e\u0648\u0627\u0647\u0645 \u062f\u0631\u0645\u0648\u0631\u062f \u0633\u0648\u0698\u0647 \u06cc\u0627\u0628\u06cc \u0635\u062d\u0628\u062a \u06a9\u0646\u0645. \u0627\u06cc\u0646\u06a9\u0647 \u0686\u0637\u0648\u0631 \u0633\u0648\u0698\u0647 \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645\u060c \u0686\u0642\u062f\u0631 \u062f\u0631 \u0645\u0648\u0631\u062f \u0622\u0646 \u067e\u0698\u0648\u0647\u0634 \u0645\u06cc \u06a9\u0646\u06cc\u0645 \u0648 \u0686\u0642\u062f\u0631 \u0627\u06cc\u0646 \u0633\u0648\u0698\u0647 \u0645\u0647\u0645 \u0627\u0633\u062a. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0627 \u0627\u06cc\u0646 \u0633\u0648\u0627\u0644 \u0631\u0648\u0628\u0631\u0648 \u0645\u06cc\u200c\u0634\u0648\u06cc\u062f \u06a9\u0647 \u0627\u06af\u0631 \u0627\u06cc\u0646 \u062d\u0631\u0641 \u0631\u0627 \u0646\u0632\u0646\u0645 \u0686\u0647 \u0627\u062a\u0641\u0627\u0642\u06cc \u0645\u06cc\u200c\u0627\u0641\u062a\u062f \u0648 \u0622\u0646 \u0648\u0642\u062a \u0627\u0633\u062a \u06a9\u0647 \u0627\u062d\u062a\u0645\u0627\u0644\u0627 \u0628\u0647 \u0627\u06cc\u0646 \u0646\u062a\u06cc\u062c\u0647 \u0645\u06cc\u200c\u0631\u0633\u06cc\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u062d\u0631\u0641 \u0628\u0627\u06cc\u062f \u06af\u0641\u062a\u0647 \u0634\u0648\u062f \u0686\u0648\u0646 \u0646\u06cc\u0627\u0632 \u062c\u0627\u0645\u0639\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u062f\u0631\u062e\u0634\u0646\u062f\u0647 \u06af\u0641\u062a: \u0645\u06cc \u062e\u0648\u0627\u0647\u0645 \u062f\u0631 \u0645\u0648\u0631\u062f \u0633\u06cc\u0646\u0645\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0635\u062d\u0628\u062a \u06a9\u0646\u0645. \u0633\u06cc\u0646\u0645\u0627\u06cc\u06cc \u06a9\u0647 \u0645\u0648\u0631\u062f \u0639\u0644\u0627\u0642\u0647 \u0627\u0645 \u0627\u0633\u062a \u0648 \u0645\u0631\u062f\u0645 \u062f\u0648\u0633\u062a \u062f\u0627\u0631\u0646\u062f. \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0627\u06cc\u0646 \u0645\u0631\u062f\u0645 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc \u06a9\u0646\u0645 \u0648 \u0646\u0645\u06cc \u062a\u0648\u0627\u0646\u0645 \u0646\u0633\u0628\u062a \u0628\u0647 \u0645\u0633\u0627\u0626\u0644\u06cc \u06a9\u0647 \u0645\u0631\u062f\u0645 \u0628\u0627 \u0622\u0646 \u062f\u0631\u06af\u06cc\u0631\u0646\u062f \u0628\u06cc \u062a\u0641\u0627\u0648\u062a \u0628\u0627\u0634\u0645.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-55\" src=\"http:\/\/www.derakhshandeh.ir\/fa\/wp-content\/uploads\/2016\/04\/pouran_darolfonun2.jpg\" alt=\"pouran_darolfonun2\" width=\"600\" height=\"400\" \/><\/p>\n<p>\u0627\u0648 \u062f\u0631\u0628\u0627\u0631\u0647 \u0633\u0648\u0698\u0647 \u06cc\u0627\u0628\u06cc \u06af\u0641\u062a: \u0645\u0639\u06cc\u0627\u0631 \u0627\u0647\u0645\u06cc\u062a \u06cc\u06a9 \u0633\u0648\u0698\u0647 \u0686\u06cc\u0633\u062a\u061f \u0686\u0637\u0648\u0631 \u0622\u0646 \u0631\u0627 \u067e\u06cc\u062f\u0627 \u0645\u06cc \u06a9\u0646\u06cc\u062f\u061f \u0628\u0631\u0627\u06cc \u0645\u0646 \u0627\u06cc\u0646 \u0637\u0648\u0631 \u0627\u062a\u0641\u0627\u0642 \u0645\u06cc\u200c\u0627\u0641\u062a\u062f. \u0647\u0645\u06cc\u0634\u0647 \u062f\u0631 \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0627 \u0645\u0633\u0627\u0626\u0644\u06cc \u06a9\u0647 \u0645\u06cc \u062e\u0648\u0627\u0647\u0645 \u062f\u0631 \u0641\u06cc\u0644\u0645 \u0647\u0627\u06cc\u0645 \u0628\u06cc\u0627\u0646 \u06a9\u0646\u0645 \u0628\u0647 \u0635\u0648\u0631\u062a \u0628\u062f\u0648\u0646 \u0648\u0627\u0633\u0637\u0647 \u0628\u0627 \u0645\u0648\u0636\u0648\u0639 \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0631\u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u0645. \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644 \u0639\u0628\u0648\u0631 \u0627\u0632 \u063a\u0628\u0627\u0631 \u0648 \u0632\u0645\u0627\u0646 \u0627\u0632 \u062f\u0633\u062a \u0631\u0641\u062a\u0647 \u0627\u0648\u0644\u06cc\u0646 \u0633\u0627\u062e\u062a\u0647 \u0647\u0627\u06cc\u0645 \u0628\u0648\u062f \u06a9\u0647 \u0628\u0627 \u0645\u062d\u0648\u0631 \u0645\u0648\u0636\u0648\u0639\u0627\u062a \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0633\u0627\u062e\u062a\u0647 \u0634\u062f \u0648 \u0647\u06cc\u0686 \u0648\u0642\u062a \u0627\u0632 \u0642\u0628\u0644 \u0633\u0648\u0698\u0647 \u0631\u0627 \u0645\u0637\u0631\u062d \u0646\u06a9\u0631\u062f\u0645 \u0686\u0631\u0627 \u06a9\u0647 \u0645\u0648\u0636\u0648\u0639 \u0641\u06cc\u0644\u0645 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0627\u0632 \u062f\u0644 \u062c\u0627\u0645\u0639\u0647 \u0627\u062a\u0641\u0627\u0642 \u0645\u06cc \u0627\u0641\u062a\u062f.<\/p>\n<p>\u06a9\u0627\u0631\u06af\u0631\u062f\u0627\u0646 \u00ab\u0628\u0686\u0647 \u0647\u0627\u06cc \u0627\u0628\u062f\u06cc\u00bb \u06af\u0641\u062a: \u0622\u062f\u0645\u200c\u0647\u0627 \u0628\u0627 \u06cc\u06a9 \u0633\u0631\u06cc \u0645\u0633\u0627\u0626\u0644 \u0631\u0648\u0628\u0631\u0648 \u0647\u0633\u062a\u0646\u062f. \u06cc\u06a9 \u0633\u0631\u06cc \u0645\u0633\u0627\u0626\u0644\u06cc \u06a9\u0647 \u0627\u062a\u0641\u0627\u0642 \u0645\u06cc\u200c\u0627\u0641\u062a\u062f \u0648 \u06a9\u0645\u062a\u0631 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u0645 \u0631\u0627\u062c\u0639 \u0628\u0647 \u0622\u0646 \u062d\u0631\u0641 \u0628\u0632\u0646\u06cc\u0645 \u0648 \u0641\u06a9\u0631 \u0645\u06cc \u06a9\u0646\u06cc\u0645 \u0627\u06cc\u0646 \u0647\u0627 \u0631\u0627 \u0646\u0645\u06cc \u062a\u0648\u0627\u0646 \u06af\u0641\u062a. \u0647\u0631 \u062d\u0631\u0641\u06cc \u0631\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0632\u062f \u0627\u0645\u0627 \u0686\u06af\u0648\u0646\u0647 \u06af\u0641\u062a\u0646\u0634 \u0645\u0647\u0645 \u0627\u0633\u062a\u060c \u0647\u0631 \u06a9\u0634\u0648\u0631\u06cc \u062e\u0637 \u0642\u0631\u0645\u0632\u0647\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f \u0648 \u0628\u0627\u06cc\u062f \u0628\u0647 \u0622\u0646 \u0627\u062d\u062a\u0631\u0627\u0645 \u06af\u0630\u0627\u0634\u062a.<\/p>\n<p>\u0627\u0648 \u0641\u06cc\u0644\u0645\u06cc \u0628\u0627 \u0645\u062d\u062a\u0648\u0627\u06cc \u0627\u0641\u0631\u0627\u062f \u0646\u0627\u0634\u0646\u0648\u0627 \u0631\u0627 \u0645\u062b\u0627\u0644 \u0632\u062f \u0648 \u06af\u0641\u062a: \u0628\u0647 \u0637\u0648\u0631 \u0645\u062b\u0627\u0644 \u0642\u0631\u0627\u0631 \u0627\u0633\u062a \u0631\u0627\u062c\u0639 \u0628\u0647 \u0646\u0627\u0634\u0646\u0648\u0627\u06cc\u06cc \u06a9\u0627\u0631 \u06a9\u0646\u0645. \u0645\u0648\u0636\u0648\u0639\u06cc \u06a9\u0647 \u0645\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u06a9\u0631\u062f\u0645\u060c \u0641\u0642\u0637 \u0633\u0631 \u0631\u0627\u0647\u0634 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0645. \u062f\u0631 \u062c\u0627\u0645\u0639\u0647 \u0627\u06cc \u06a9\u0647 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc \u06a9\u0646\u0645 \u0645\u062a\u0648\u062c\u0647 \u0645\u06cc \u0634\u0648\u0645 \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u0646\u0627\u0634\u0646\u0648\u0627 \u0627\u0632 \u0633\u0647\u0645 \u0632\u0646\u062f\u06af\u06cc \u0634\u0627\u0646 \u0628\u06cc \u0628\u0647\u0631\u0647\u200c\u0627\u0646\u062f. \u0627\u06a9\u062b\u0631 \u0627\u06cc\u0646 \u0628\u0686\u0647 \u0647\u0627 \u0628\u0627 \u0645\u0634\u06a9\u0644\u0627\u062a\u06cc \u0631\u0648\u0628\u0631\u0648 \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0631\u0648\u0627\u0646\u0634\u0627\u0646 \u0631\u062e \u0645\u06cc\u200c\u062f\u0647\u062f. \u0627\u06cc\u0646\u062c\u0627 \u062c\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0633\u0648\u0698\u0647\u060c \u0645\u0646 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u06cc \u06a9\u0646\u062f \u0648 \u0645\u0646 \u062f\u0631 \u0645\u0633\u06cc\u0631\u06cc \u0642\u0631\u0627\u0631 \u0645\u06cc \u06af\u06cc\u0631\u0645 \u06a9\u0647 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644\u0634 \u0628\u0631\u0648\u0645. \u062f\u0631 \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0627 \u0645\u0634\u06a9\u0644\u0627\u062a\u06cc \u06a9\u0647 \u0637\u06cc \u062a\u062d\u0642\u06cc\u0642 \u0628\u0627 \u0622\u0646 \u0631\u0648\u0628\u0631\u0648 \u0645\u06cc \u0634\u0648\u0645 \u0628\u0647 \u0648\u062c\u0648\u062f \u0645\u06cc \u0622\u06cc\u062f \u0628\u0686\u0647 \u0647\u0627 \u062e\u0648\u062f\u0634\u0627\u0646 \u0627\u0648\u0644\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0645\u0646 \u0647\u0633\u062a\u0646\u062f \u0645\u0646 \u0628\u0627\u06cc\u062f \u0646\u0645\u0648\u0646\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0645.<\/p>\n<p>\u0627\u06cc\u0646 \u06a9\u0627\u0631\u06af\u0631\u062f\u0627\u0646 \u0628\u0631\u0627\u06cc \u0622\u06af\u0627\u0647\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u06af\u0633\u062a\u0631\u062f\u06af\u06cc \u0627\u06cc\u0646 \u0645\u0633\u0627\u0644\u0647 \u06af\u0641\u062a: \u0686\u0637\u0648\u0631 \u0628\u0627\u06cc\u062f \u0628\u062f\u0627\u0646\u0645 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u06af\u0633\u062a\u0631\u062f\u0647 \u0627\u0633\u062a \u0648 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u06cc\u06a9 \u0646\u0641\u0631 \u0646\u0645\u06cc \u0634\u0648\u062f. \u067e\u0633 \u0628\u0627 \u0628\u0686\u0647 \u0647\u0627\u06cc \u0646\u0627\u0634\u0646\u0648\u0627 \u0635\u062d\u0628\u062a \u0645\u06cc \u06a9\u0646\u0645. \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u0632\u0628\u0627\u0646 \u0627\u0634\u0627\u0631\u0647 \u0634\u0627\u0646 \u0631\u0627 \u06cc\u0627\u062f \u0628\u06af\u06cc\u0631\u0645\u060c \u0633\u0631\u06a9\u0644\u0627\u0633 \u0634\u0627\u0646 \u0645\u06cc\u200c\u0646\u0634\u06cc\u0646\u0645 \u062a\u0627 \u0628\u062f\u0627\u0646\u0645 \u0686\u0637\u0648\u0631 \u0628\u0627\u06cc\u062f \u0628\u0627 \u0627\u0648 \u0631\u0627\u0628\u0637\u0647 \u0628\u0631\u0642\u0631\u0627\u0631 \u06a9\u0646\u0645. \u0627\u0632 \u0637\u0631\u0641\u06cc \u0641\u06a9\u0631 \u0645\u06cc \u06a9\u0646\u0645 \u0627\u06cc\u0646 \u067e\u0633\u0631 \u06cc\u0627 \u062f\u062e\u062a\u0631 \u0628\u0627 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u067e\u0633 \u0633\u0631\u0627\u063a \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0647\u0627\u06cc\u0634\u0627\u0646 \u0645\u06cc\u200c\u0631\u0648\u0645. \u0639\u0644\u062a \u067e\u0631\u062e\u0627\u0634\u06af\u0631\u06cc \u0686\u06cc\u0633\u062a \u0648 \u0686\u0631\u0627 \u0627\u06cc\u0646 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u062f\u0631 \u062e\u0627\u0646\u0647 \u0646\u0627 \u0622\u0631\u0627\u0645\u0646\u062f. \u067e\u0633 \u0628\u0627\u06cc\u062f \u0628\u0631\u0627\u06cc \u062a\u0645\u0627\u0645 \u0627\u06cc\u0646 \u0686\u0631\u0627\u0647\u0627 \u0628\u0647 \u062c\u0648\u0627\u0628 \u0628\u0631\u0633\u0645. \u00a0\u0648\u0627\u0642\u0639\u06cc\u062a \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062c\u0627\u0645\u0639\u0647 \u0628\u0647 \u0627\u0648 \u0641\u0631\u0635\u062a \u0646\u0645\u06cc \u062f\u0647\u062f\u060c \u0627\u0645\u06a9\u0627\u0646 \u0646\u0645\u06cc \u062f\u0647\u062f\u060c \u0648\u0642\u062a \u0646\u0645\u06cc \u062f\u0647\u062f \u062a\u0627 \u0645\u062b\u0644 \u0628\u0642\u06cc\u0647 \u0633\u0647\u0645\u06cc \u0628\u0628\u0631\u062f. \u062f\u0631 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0647\u0645 \u062c\u0648\u0627\u0628\u06cc \u0628\u0647 \u0633\u0648\u0627\u0644\u0627\u062a\u0634 \u0646\u0645\u06cc\u200c\u062f\u0647\u0646\u062f. \u0622\u062f\u0645 \u0634\u0646\u0648\u0627 \u0631\u0627\u062d\u062a \u0628\u0647 \u062e\u0648\u0627\u0633\u062a\u0647 \u0647\u0627\u06cc\u0634 \u062f\u0631 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0645\u06cc \u0631\u0633\u062f \u0627\u0645\u0627 \u06cc\u06a9 \u0646\u0627\u0634\u0646\u0648\u0627 \u0628\u0647 \u062e\u0648\u0627\u0633\u062a\u0647 \u0647\u0627\u06cc\u0634 \u0646\u0645\u06cc \u0631\u0633\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u062d\u0633\u0627\u0633\u06cc\u062a\u0645 \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u0646\u0645\u06cc \u062f\u0647\u0645 \u0648 \u0645\u06cc \u06af\u0648\u06cc\u0645 \u0645\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0634\u062f\u0647 \u0627\u0645 \u062a\u0627 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0631\u0627 \u067e\u06cc\u0634 \u0628\u0628\u0631\u0645.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-56\" src=\"http:\/\/www.derakhshandeh.ir\/fa\/wp-content\/uploads\/2016\/04\/pouran_darolfonun3.jpg\" alt=\"pouran_darolfonun3\" width=\"600\" height=\"400\" \/><\/p>\n<p>\u0627\u0648 \u062f\u0631\u0628\u0627\u0631\u0647 \u0627\u062f\u0627\u0645\u0647 \u0627\u06cc\u0646 \u0631\u0648\u0646\u062f \u0627\u0641\u0632\u0648\u062f: \u0645\u0631\u062d\u0644\u0647 \u0628\u0639\u062f \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0627\u06cc \u0627\u0633\u062a. \u0628\u0627 \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u0633\u060c \u062c\u0627\u0645\u0639\u0647 \u0634\u0646\u0627\u0633 \u0648 \u0645\u0639\u0644\u0645\u0627\u0646 \u0628\u0647 \u0637\u0648\u0631 \u062c\u062f\u0627\u06af\u0627\u0646\u0647 \u0635\u062d\u0628\u062a \u0645\u06cc \u06a9\u0646\u0645. \u067e\u0633 \u067e\u0698\u0648\u0647\u0634\u06cc \u062f\u0627\u0634\u062a\u0647 \u0627\u0645 \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u067e\u0698\u0648\u0647\u0634 \u0645\u06cc \u06af\u0648\u06cc\u062f \u0628\u0639\u062f \u0631\u0648\u0627\u0646\u0634\u0646\u0627\u062e\u062a\u06cc \u0627\u06cc\u0646 \u062f\u0627\u0633\u062a\u0627\u0646 \u062e\u06cc\u0644\u06cc \u0645\u0647\u0645 \u0627\u0633\u062a.<\/p>\n<p>\u062f\u0631\u062e\u0634\u0646\u062f\u0647 \u062a\u0635\u0631\u06cc\u062d \u06a9\u0631\u062f: \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0645\u06cc \u06af\u0648\u06cc\u0645 \u0622\u06cc\u0627 \u0628\u0631 \u0627\u0633\u0627\u0633 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a\u06cc \u06a9\u0647 \u0628\u0647 \u062f\u0633\u062a \u0622\u0648\u0631\u062f\u0647 \u0627\u0645 \u0627\u06cc\u0646 \u0641\u06cc\u0644\u0645 \u0628\u0627\u06cc\u062f \u0633\u0627\u062e\u062a\u0647 \u0634\u0648\u062f \u06cc\u0627 \u062e\u06cc\u0631. \u0627\u06af\u0631 \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0646\u067e\u0631\u062f\u0627\u0632\u0645 \u0686\u0647 \u0627\u062a\u0641\u0627\u0642\u06cc \u0645\u06cc \u0627\u0641\u062a\u062f \u067e\u0633 \u0628\u0647 \u0646\u062a\u06cc\u062c\u0647 \u0645\u06cc \u0631\u0633\u0645 \u06a9\u0647 \u0646\u0627\u0634\u0646\u0648\u0627\u06cc\u0627\u0646 \u062c\u0627\u0645\u0639\u0647 \u062f\u06cc\u062f\u0647 \u0645\u06cc \u0634\u0648\u0646\u062f.\u067e\u0633 \u0646\u0648\u0634\u062a\u0646 \u0641\u06cc\u0644\u0645\u0646\u0627\u0645\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0622\u063a\u0627\u0632 \u0645\u06cc \u0634\u0648\u062f.<\/p>\n<p>\u0627\u06cc\u0646 \u0641\u06cc\u0644\u0645\u0633\u0627\u0632 \u0627\u062f\u0627\u0645\u0647 \u062f\u0627\u062f: \u0645\u0631\u062d\u0644\u0647 \u0628\u0639\u062f \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0627\u0632\u06cc\u06af\u0631 \u0627\u0633\u062a. \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0628\u0627\u0632\u06cc \u0646\u0642\u0634 \u0641\u0631\u062f \u0646\u0627\u0634\u0646\u0648\u0627 \u0628\u0631\u0627\u06cc \u0628\u0627\u0632\u06cc\u06af\u0631\u0627\u0646 \u062d\u0631\u0641\u0647 \u0627\u06cc \u06cc\u06a9 \u0641\u0631\u0635\u062a \u0627\u0633\u062a \u062a\u0635\u0645\u06cc\u0645 \u0645\u06cc \u06af\u06cc\u0631\u0645 \u0627\u0632 \u06cc\u06a9 \u0646\u0627\u0628\u0627\u0632\u06cc\u06af\u0631 \u0646\u0627\u0634\u0646\u0648\u0627 \u06a9\u0645\u06a9 \u0628\u06af\u06cc\u0631\u0645. \u062a\u0648\u0627\u0646\u0645\u0646\u062f\u06cc \u0647\u0627\u06cc\u0634 \u0631\u0627 \u0645\u06cc \u0633\u0646\u062c\u0645. \u0647\u0632\u06cc\u0646\u0647 \u0641\u06cc\u0644\u0645 \u0633\u06cc\u0646\u0645\u0627\u06cc\u06cc \u062e\u06cc\u0644\u06cc \u0632\u06cc\u0627\u062f \u0627\u0633\u062a \u0648 \u0628\u0627\u06cc\u062f \u0622\u06af\u0627\u0647\u0627\u0646\u0647 \u062c\u0644\u0648 \u0628\u0631\u0648\u0645 \u0686\u0631\u0627 \u06a9\u0647 \u0628\u0627\u06cc\u062f \u067e\u0648\u0644 \u0641\u06cc\u0644\u0645 \u0628\u0631\u06af\u0631\u062f\u062f \u067e\u0633 \u0628\u0627\u06cc\u062f \u062f\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0627\u0632\u06cc\u06af\u0631 \u062f\u0642\u062a \u06a9\u0646\u0645. \u067e\u0633 \u0627\u0632 \u06cc\u06a9 \u0627\u0646\u062a\u062e\u0627\u0628 \u062e\u06cc\u0644\u06cc \u0633\u062e\u062a \u0628\u0627 \u0628\u06cc\u0634 \u0627\u0632 \u06f2\u06f0\u06f0\u0646\u0641\u0631 \u0645\u0635\u0627\u062d\u0628\u0647 \u06a9\u0631\u062f\u0645 \u0648 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u0646\u062f\u0647 \u0634\u062f\u0647 \u062a\u0631\u06cc\u0646 \u0646\u0627\u0634\u0646\u0648\u0627\u06cc\u0627\u0646 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0631\u062f\u0645.<\/p>\n<p>\u0648\u06cc \u062a\u0623\u06a9\u06cc\u062f \u06a9\u0631\u062f: \u0633\u0648\u0698\u0647 \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u06a9\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u06cc \u06a9\u0646\u06cc\u062f \u0628\u0627\u06cc\u062f \u0627\u0632 \u06cc\u06a9 \u0645\u062d\u062f\u0648\u062f\u0647 \u0648\u0633\u06cc\u0639 \u062a\u0631\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0634\u0648\u062f. \u0627\u06af\u0631 \u0633\u0648\u0698\u0647 \u0645\u0648\u0631\u062f \u0646\u0638\u0631 \u0645\u062d\u062f\u0648\u062f\u0647 \u06a9\u0648\u0686\u06a9\u06cc \u062f\u0627\u0631\u062f\u060c \u067e\u0633 \u0627\u06af\u0631 \u062f\u0631\u0645\u0648\u0631\u062f \u0622\u0646 \u0641\u06cc\u0644\u0645 \u0646\u0633\u0627\u0632\u06cc\u062f \u0647\u0645 \u0627\u062a\u0641\u0627\u0642\u06cc \u0646\u0645\u06cc \u0627\u0641\u062a\u062f.<\/p>\n<p>\u062f\u0631\u062e\u0634\u0646\u062f\u0647 \u06af\u0641\u062a: \u0641\u06cc\u0644\u0645 \u00ab\u0647\u06cc\u0633! \u062f\u062e\u062a\u0631\u0647\u0627 \u0641\u0631\u06cc\u0627\u062f \u0646\u0645\u06cc \u0632\u0646\u0646\u062f\u00bb \u0647\u0645 \u0633\u0648\u0698\u0647 \u0627\u06cc \u0628\u0648\u062f \u06a9\u0647 \u0632\u06cc\u0631 \u067e\u0648\u0633\u062a \u0634\u0647\u0631 \u0627\u062f\u0627\u0645\u0647 \u062f\u0627\u0634\u062a. \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u062f\u0631 \u0647\u0645\u0647 \u062c\u0627\u06cc \u062f\u0646\u06cc\u0627 \u062f\u0631 \u062d\u0627\u0644 \u0627\u062a\u0641\u0627\u0642 \u0627\u0633\u062a. \u06a9\u0648\u062f\u06a9 \u0622\u0632\u0627\u0631\u06cc \u0645\u0633\u0627\u0644\u0647 \u0645\u0647\u0645\u06cc \u0627\u0633\u062a \u0628\u0647 \u0627\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u06a9\u0647 \u062e\u06cc\u0644\u06cc \u0627\u0632 \u0645\u062d\u062f\u0648\u062f\u06cc\u062a \u0647\u0627 \u0645\u0627 \u0631\u0627 \u0648\u0627\u062f\u0627\u0631 \u0645\u06cc \u06a9\u0646\u062f \u06a9\u0647 \u0633\u06a9\u0648\u062a \u06a9\u0646\u06cc\u0645 \u0627\u0645\u0627 \u0645\u0646 \u0622\u062f\u0645\u200c\u0647\u0627\u06cc \u0645\u0631\u062f\u0647 \u0645\u062a\u062d\u0631\u06a9\u06cc \u0631\u0627 \u0645\u06cc \u062f\u06cc\u062f\u0645 \u06a9\u0647 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0645\u0627 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc \u06a9\u0646\u0646\u062f \u0627\u0645\u0627 \u0645\u0631\u062f\u0647 \u0627\u0646\u062f. \u067e\u0633 \u062a\u0635\u0645\u06cc\u0645 \u06af\u0631\u0641\u062a\u0645 \u062f\u0631 \u0627\u06cc\u0646 \u0632\u0645\u06cc\u0646\u0647 \u0641\u06cc\u0644\u0645 \u0628\u0633\u0627\u0632\u0645.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-57\" src=\"http:\/\/www.derakhshandeh.ir\/fa\/wp-content\/uploads\/2016\/04\/pouran_darolfonun4.jpg\" alt=\"pouran_darolfonun4\" width=\"600\" height=\"400\" \/><\/p>\n<p>\u0648\u06cc \u062f\u0631\u0628\u0627\u0631\u0647 \u0645\u0631\u0632 \u0628\u06cc\u0646 \u0634\u0639\u0627\u0631\u06cc \u0634\u062f\u0646 \u0648 \u0646\u0634\u062f\u0646 \u0633\u0648\u0698\u0647 \u06af\u0641\u062a: \u0645\u0631\u0632 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0631\u06cc\u06a9\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f. \u0627\u0628\u062a\u062f\u0627 \u0633\u0639\u06cc \u0645\u06cc \u06a9\u0646\u0645 \u0628\u0627\u0648\u0631 \u067e\u0630\u06cc\u0631\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u062e\u0648\u062f\u0645 \u0645\u0644\u0627\u06a9 \u0642\u0631\u0627\u0631 \u062f\u0647\u0645. \u0627\u0646\u0642\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0628\u0627\u06cc\u062f \u0628\u0627\u0648\u0631\u067e\u0630\u06cc\u0631 \u0648 \u06af\u0633\u062a\u0631\u062f\u0647 \u0628\u0627\u0634\u062f \u062a\u0627 \u0645\u062e\u0627\u0637\u0628\u0627\u0646 \u0622\u0646\u0631\u0627 \u062f\u0631\u06a9 \u06a9\u0646\u0646\u062f \u0648 \u0634\u0639\u0627\u0631 \u0646\u0634\u0648\u062f. \u0627\u06af\u0631 \u0634\u0639\u0627\u0631 \u0634\u0648\u062f \u0647\u06cc\u0686 \u0648\u0642\u062a \u0645\u0648\u0641\u0642 \u0646\u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f. \u0645\u0631\u062f\u0645 \u0634\u0639\u0627\u0631 \u0646\u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u0646\u062f \u0645\u0631\u062f\u0645 \u0648\u0627\u0642\u0639\u06cc\u062a \u0647\u0627 \u0631\u0627 \u0628\u062f\u0648\u0646 \u0648\u0627\u0633\u0637\u0647 \u0645\u06cc \u062e\u0648\u0627\u0647\u0646\u062f. \u0645\u0647\u0645 \u062a\u0631\u06cc\u0646 \u0641\u0627\u06a9\u062a\u0648\u0631 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0641\u06cc\u0644\u0645\u0633\u0627\u0632 \u0628\u0627\u06cc\u062f \u0628\u062f\u0648\u0646 \u0648\u0627\u0633\u0637\u0647 \u0648 \u0628\u062f\u0648\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u062e\u0648\u062f\u0634 \u0631\u0627 \u0633\u0627\u0646\u0633\u0648\u0631 \u06a9\u0646\u062f \u062a\u0645\u0627\u0645 \u06a9\u0646\u062f \u0645\u0648\u0636\u0648\u0639 \u0631\u0627 \u0645\u0637\u0631\u062d \u06a9\u0646\u062f. \u0645\u062e\u0627\u0637\u0628 \u0632\u0645\u0627\u0646\u06cc \u0628\u0647 \u0633\u0645\u062a \u0634\u0645\u0627 \u0645\u06cc \u0622\u06cc\u062f \u06a9\u0647 \u0627\u062d\u0633\u0627\u0633 \u06a9\u0646\u062f \u0633\u0648\u0698\u0647 \u0648\u0627\u0642\u0639\u06cc \u0627\u0633\u062a \u0648 \u062e\u0648\u062f\u0650 \u062e\u0648\u062f \u0632\u0646\u062f\u06af\u06cc \u0627\u0633\u062a. \u062c\u062f\u0627\u06cc\u06cc \u0646\u0627\u062f\u0631 \u0627\u0632 \u0633\u06cc\u0645\u06cc\u0646 \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0645\u0648\u0631\u062f \u062a\u0648\u062c\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc \u06af\u06cc\u0631\u062f \u06a9\u0647 \u0628\u0627\u0632\u06cc\u06af\u0631\u0627\u0646\u0634 \u0646\u0642\u0634 \u0622\u062f\u0645 \u0647\u0627\u06cc\u06cc \u0631\u0627 \u0628\u0627\u0632\u06cc \u0645\u06cc \u06a9\u0646\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0627\u0637\u0631\u0627\u0641\u0645\u0627\u0646 \u062f\u0627\u0631\u0646\u062f \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc \u06a9\u0646\u0646\u062f.<\/p>\n<p>\u0627\u06cc\u0646 \u06a9\u0627\u0631\u06af\u0631\u062f\u0627\u0646 \u0647\u0645\u0686\u0646\u06cc\u0646 \u062f\u0631\u0628\u0627\u0631\u0647 \u0641\u06cc\u0644\u0645 \u0647\u0627\u06cc \u0641\u0645\u0646\u06cc\u0633\u062a\u06cc \u0648 \u0641\u06cc\u0644\u0645\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0631\u0627\u062c\u0639 \u0628\u0647 \u0632\u0646\u0627\u0646 \u0633\u0627\u062e\u062a\u0647 \u0645\u06cc \u0634\u0648\u062f\u060c \u062a\u0635\u0631\u06cc\u062d \u06a9\u0631\u062f: \u0627\u06af\u0631 \u062f\u0627\u0631\u06cc\u0645 \u0628\u0647 \u0645\u0648\u0636\u0648\u0639\u06cc \u06a9\u0647 \u0632\u0646 \u0642\u0647\u0631\u0645\u0627\u0646 \u062f\u0627\u0633\u062a\u0627\u0646 \u0627\u0633\u062a \u0645\u06cc \u067e\u0631\u062f\u0627\u0632\u06cc\u0645 \u0641\u0645\u0646\u06cc\u0633\u062a\u06cc \u0627\u0633\u062a. \u0627\u0645\u0627 \u0648\u0642\u062a\u06cc \u0627\u0632 \u0646\u0627\u0628\u0631\u0627\u0628\u0631\u06cc \u0647\u0627 \u062d\u0631\u0641 \u0645\u06cc \u0632\u0646\u06cc\u0645 \u0627\u06cc\u0646 \u0646\u0627\u0628\u0631\u0627\u0628\u0631\u06cc \u0647\u0627 \u0628\u0647 \u0645\u0639\u0646\u0627\u06cc \u0641\u0645\u0646\u06cc\u0633\u062a\u06cc \u0646\u06cc\u0633\u062a. \u0627\u06af\u0631 \u0627\u0632 \u062d\u0642\u0648\u0642 \u06cc\u06a9 \u0627\u0646\u0633\u0627\u0646 \u062f\u0641\u0627\u0639 \u0645\u06cc \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0622\u0646 \u0627\u0646\u0633\u0627\u0646 \u0632\u0646 \u0627\u0633\u062a\u060c \u0627\u0633\u0645\u0634 \u0641\u0645\u0646\u06cc\u0633\u062a \u0646\u06cc\u0633\u062a.<\/p>\n<p>\u0627\u0648 \u0628\u0627\u0631 \u062f\u06cc\u06af\u0631 \u062a\u0623\u06a9\u06cc\u062f \u06a9\u0631\u062f \u06a9\u0647 \u062f\u0631 \u0633\u0627\u062e\u062a \u0641\u06cc\u0644\u0645 \u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc\u060c \u0641\u0627\u06a9\u062a\u0648\u0631 \u0627\u0635\u0644\u06cc \u0648\u0627\u0642\u0639\u06cc\u062a \u0648 \u06af\u0633\u062a\u0631\u062f\u06af\u06cc \u0622\u0646 \u0627\u0633\u062a.<\/p>\n<p>\u062f\u0631\u062e\u0634\u0646\u062f\u0647 \u06cc\u0627\u062f\u0622\u0648\u0631 \u0634\u062f: \u0633\u06cc\u0646\u0645\u0627 \u06cc\u0639\u0646\u06cc \u0632\u0646\u062f\u06af\u06cc. \u062a\u0627 \u0628\u0627 \u0622\u0646 \u0632\u0646\u062f\u06af\u06cc \u0646\u06a9\u0646\u06cc\u062f\u060c \u0646\u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0631\u0648\u06cc \u0645\u0631\u062f\u0645 \u062a\u0623\u062b\u06cc\u0631 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f. \u067e\u0633 \u0627\u0632 \u062a\u062d\u0642\u06cc\u0642 \u062f\u0631 \u0645\u0648\u0631\u062f \u0645\u0648\u0636\u0648\u0639\u0627\u062a \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0628\u0627\u06cc\u062f \u0632\u0628\u0627\u0646\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0628\u0627 \u0631\u0639\u0627\u06cc\u062a \u062e\u0637 \u0642\u0631\u0645\u0632\u0647\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u062d\u0631\u0641\u062a\u0627\u0646 \u0631\u0627 \u0628\u0632\u0646\u06cc\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0632\u0628\u0627\u0646 \u0628\u0627\u06cc\u062f \u062d\u0631\u0645\u062a \u062c\u0627\u0645\u0639\u0647 \u0631\u0627 \u0631\u0639\u0627\u06cc\u062a \u06a9\u0646\u06cc\u062f \u0648 \u0627\u0646\u062a\u062e\u0627\u0628 \u0627\u06cc\u0646 \u0632\u0628\u0627\u0646 \u0628\u0631\u0639\u0647\u062f\u0647 \u06a9\u0627\u0631\u06af\u0631\u062f\u0627\u0646 \u0648 \u0646\u0648\u06cc\u0633\u0646\u062f\u0647 \u0627\u0633\u062a. \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0646 \u0627\u06cc\u0646 \u0632\u0628\u0627\u0646 \u06a9\u0627\u0631 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0647\u0645\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062a\u0646\u0647\u0627 \u0644\u0627\u0632\u0645\u0647 \u0622\u0646 \u0639\u0634\u0642 \u0627\u0633\u062a. \u0627\u06af\u0631 \u06a9\u0627\u0631\u06af\u0631\u062f\u0627\u0646 \u0639\u0627\u0634\u0642 \u0628\u0627\u0634\u062f \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0634\u06a9\u0644 \u0645\u0648\u0636\u0648\u0639 \u0631\u0627 \u0645\u0637\u0631\u062d \u06a9\u0646\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u06a9\u0627\u0631\u06af\u0631\u062f\u0627\u0646 \u0641\u06cc\u0644\u0645 \u0633\u06cc\u0646\u0645\u0627\u06cc\u06cc \u00ab\u0647\u06cc\u0633! \u062f\u062e\u062a\u0631\u0647\u0627 \u0641\u0631\u06cc\u0627\u062f \u0646\u0645\u06cc\u200c\u0632\u0646\u0646\u062f\u00bb \u062a\u0627\u06a9\u06cc\u062f \u06a9\u0631\u062f \u0641\u06cc\u0644\u0645\u0633\u0627\u0632 \u0628\u0627\u06cc\u062f \u0628\u0627 \u0633\u0648\u0698\u0647 \u0632\u0646\u062f\u06af\u06cc \u06a9\u0646\u062f.<\/p>\n","protected":false},"author":1,"featured_media":54,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[2,8],"class_list":["post-53","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-7","tag-2","tag-8"],"_links":{"self":[{"href":"http:\/\/pouranderakhshandeh.ir\/fa\/wp-json\/wp\/v2\/posts\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/pouranderakhshandeh.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/pouranderakhshandeh.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/pouranderakhshandeh.ir\/fa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/pouranderakhshandeh.ir\/fa\/wp-json\/wp\/v2\/comments?post=53"}],"version-history":[{"count":1,"href":"http:\/\/pouranderakhshandeh.ir\/fa\/wp-json\/wp\/v2\/posts\/53\/revisions"}],"predecessor-version":[{"id":58,"href":"http:\/\/pouranderakhshandeh.ir\/fa\/wp-json\/wp\/v2\/posts\/53\/revisions\/58"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/pouranderakhshandeh.ir\/fa\/wp-json\/wp\/v2\/media\/54"}],"wp:attachment":[{"href":"http:\/\/pouranderakhshandeh.ir\/fa\/wp-json\/wp\/v2\/media?parent=53"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/pouranderakhshandeh.ir\/fa\/wp-json\/wp\/v2\/categories?post=53"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/pouranderakhshandeh.ir\/fa\/wp-json\/wp\/v2\/tags?post=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}